{"id":131,"date":"2025-10-20T17:39:21","date_gmt":"2025-10-20T17:39:21","guid":{"rendered":"https:\/\/beige-mule-676484.hostingersite.com\/?page_id=131"},"modified":"2026-07-17T13:45:58","modified_gmt":"2026-07-17T16:45:58","slug":"quero-contratar","status":"publish","type":"page","link":"https:\/\/keepgomarket.com\/en\/quero-contratar\/","title":{"rendered":"Want to hire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"131\" class=\"elementor elementor-131\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae28504 e-flex e-con-boxed e-con e-parent\" data-id=\"ae28504\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9425931 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9425931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Leve a Keep &amp; Go para o seu espa\u00e7o\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8889d4c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8889d4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Um minimercado aut\u00f4nomo que valoriza o empreendimento e facilita a rotina de quem utiliza.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd13e9f e-con-full e-flex e-con e-child\" data-id=\"fd13e9f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9823e7b elementor-mobile-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"9823e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar proposta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fb32b02 e-flex e-con-boxed e-con e-parent\" data-id=\"5fb32b02\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7efd0660 e-con-full e-flex e-con e-child\" data-id=\"7efd0660\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8d4c3b elementor-widget elementor-widget-heading\" data-id=\"f8d4c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Onde a Keep &amp; Go pode estar\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bda52ea elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4bda52ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Condom\u00ednios residenciais<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Condom\u00ednios comerciais<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Empresas e escrit\u00f3rios<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Empreendimentos novos ou j\u00e1 em opera\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-def65e1 e-con-full e-flex e-con e-child\" data-id=\"def65e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74f40c9e elementor-widget elementor-widget-image\" data-id=\"74f40c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking.jpg\" class=\"attachment-full size-full wp-image-462\" alt=\"\" srcset=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking.jpg 2560w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking-300x169.jpg 300w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking-1024x576.jpg 1024w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking-768x432.jpg 768w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking-1536x864.jpg 1536w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking-2048x1152.jpg 2048w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_building_parking-18x10.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a09ac44 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"2a09ac44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_elderly-768x1024.jpg\" class=\"attachment-large size-large wp-image-419\" alt=\"\" srcset=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_elderly-768x1024.jpg 768w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_elderly-225x300.jpg 225w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_elderly-9x12.jpg 9w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_elderly.jpg 1056w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32754f1b elementor-widget__width-auto elementor-absolute animated-slow elementor-invisible elementor-widget elementor-widget-elementskit-video\" data-id=\"32754f1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;ekit_video_popup_close_icon&quot;:{&quot;value&quot;:&quot;icon icon-cancel&quot;,&quot;library&quot;:&quot;ekiticons&quot;}}\" data-widget_type=\"elementskit-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"video-content\" data-video-player=\"[]\" data-video-setting=\"{&quot;videoVolume&quot;:&quot;horizontal&quot;,&quot;startVolume&quot;:0.8,&quot;videoType&quot;:&quot;iframe&quot;,&quot;videoClass&quot;:&quot;mfp-fade&quot;,&quot;popupIcon&quot;:{&quot;value&quot;:&quot;icon icon-cancel&quot;,&quot;library&quot;:&quot;ekiticons&quot;},&quot;videoStyle&quot;:&quot;popup&quot;,&quot;videoTypeName&quot;:&quot;youtube&quot;,&quot;autoplay&quot;:false,&quot;muted&quot;:false,&quot;loop&quot;:false,&quot;bg_color&quot;:&quot;&quot;}\">\n\t\t\t\t\t<div class=\"ekit-hidden-icons\" style=\"display: none;\">\n\t\t\t<div class=\"ekit-popup-close-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-cancel\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<a class=\"ekit_icon_button glow-ripple ekit-video-popup ekit-video-popup-btn\" href=\"https:\/\/www.youtube.com\/embed\/VhBl3dHT5SY?feature=oembed?playlist=VhBl3dHT5SY&amp;mute=0&amp;autoplay=0&amp;loop=no&amp;controls=0&amp;start=0&amp;end=\" aria-label=\"video-popup\" target=\"_blank\" rel=\"noopener\">\n    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg><\/a>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92b8604 e-flex e-con-boxed e-con e-parent\" data-id=\"92b8604\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-379fd16 e-con-full e-flex e-con e-child\" data-id=\"379fd16\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34a413d elementor-vertical-align-middle elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"34a413d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Atende todas as responsabilidades e exig\u00eancias necess\u00e1rias perante os \u00f3rg\u00e3os existentes.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-880f13d e-con-full e-flex e-con e-child\" data-id=\"880f13d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a83fe8b elementor-widget elementor-widget-heading\" data-id=\"a83fe8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Benef\u00edcios para o condom\u00ednio \/ empresa<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae6343a elementor-widget elementor-widget-text-editor\" data-id=\"ae6343a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conveni\u00eancia e praticidade 24h<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Valoriza\u00e7\u00e3o do im\u00f3vel<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Custo zero de implanta\u00e7\u00e3o<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comissionamento sobre as vendas<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mais seguran\u00e7a para moradores e usu\u00e1rios<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Projeto ajustado ao espa\u00e7o dispon\u00edvel<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39d4fb59 e-flex e-con-boxed e-con e-parent\" data-id=\"39d4fb59\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b53099 e-flex e-con-boxed e-con e-child\" data-id=\"5b53099\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-227a02d7 elementor-widget elementor-widget-heading\" data-id=\"227a02d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Como funciona na pr\u00e1tica<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cbdc8b3 e-con-full e-flex e-con e-child\" data-id=\"5cbdc8b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f0acbce e-con-full e-flex e-con e-child\" data-id=\"f0acbce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b202346 e-con-full e-flex e-con e-child\" data-id=\"b202346\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-374425d animated-slow e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"374425d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1495b22 elementor-widget elementor-widget-heading\" data-id=\"1495b22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a98611 elementor-widget elementor-widget-heading\" data-id=\"2a98611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">An\u00e1lise do espa\u00e7o<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-affb8db e-con-full e-flex e-con e-child\" data-id=\"affb8db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ce942ac animated-slow e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"ce942ac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8eb29 elementor-widget elementor-widget-heading\" data-id=\"2f8eb29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6120489 elementor-widget elementor-widget-heading\" data-id=\"6120489\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Projeto personalizado<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16e0794 e-con-full e-flex e-con e-child\" data-id=\"16e0794\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d9f6f56 animated-slow e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"d9f6f56\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28b7529 elementor-widget elementor-widget-heading\" data-id=\"28b7529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab186bc elementor-widget elementor-widget-heading\" data-id=\"ab186bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Instala\u00e7\u00e3o e adequa\u00e7\u00f5es<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4dd199 e-con-full e-flex e-con e-child\" data-id=\"a4dd199\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8d8960 animated-slow e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"a8d8960\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a89e7e3 elementor-widget elementor-widget-heading\" data-id=\"a89e7e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7400ce1 elementor-widget elementor-widget-heading\" data-id=\"7400ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Abastecimento e inaugura\u00e7\u00e3o<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf5a2c3 e-con-full e-flex e-con e-child\" data-id=\"cf5a2c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-53d0586 animated-slow e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"53d0586\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e15c55d elementor-widget elementor-widget-heading\" data-id=\"e15c55d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2321089 elementor-widget elementor-widget-heading\" data-id=\"2321089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Opera\u00e7\u00e3o, reposi\u00e7\u00e3o e suporte cont\u00ednuo<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e278cbf e-flex e-con-boxed e-con e-child\" data-id=\"1e278cbf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-640df7fc e-flex e-con-boxed e-con e-child\" data-id=\"640df7fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc73c70 elementor-widget elementor-widget-heading\" data-id=\"5dc73c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quer levar mais praticidade para o seu espa\u00e7o?\nFale com a Keep &amp; Go e solicite uma proposta personalizada.\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ddbb062 e-flex e-con-boxed e-con e-parent\" data-id=\"3ddbb062\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-63c53a72 e-con-full e-flex e-con e-child\" data-id=\"63c53a72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-592ab0f elementor-widget elementor-widget-n-carousel\" data-id=\"592ab0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;e25b611&quot;},{&quot;slide_title&quot;:&quot;Slide #2&quot;,&quot;_id&quot;:&quot;76e1b7d&quot;},{&quot;slide_title&quot;:&quot;Slide #3&quot;,&quot;_id&quot;:&quot;b87a85b&quot;}],&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:4000,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b2c97a e-flex e-con-boxed e-con e-child\" data-id=\"4b2c97a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22a3dac elementor-widget elementor-widget-image\" data-id=\"22a3dac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1056\" height=\"1408\" src=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_skater.jpg\" class=\"attachment-full size-full wp-image-465\" alt=\"\" srcset=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_skater.jpg 1056w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_skater-225x300.jpg 225w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_skater-768x1024.jpg 768w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/05\/keepgo_skater-9x12.jpg 9w\" sizes=\"(max-width: 1056px) 100vw, 1056px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14ba3d e-flex e-con-boxed e-con e-child\" data-id=\"e14ba3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83fdb19 elementor-widget elementor-widget-image\" data-id=\"83fdb19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/04\/IMG_3591-768x1024.jpg\" class=\"attachment-large size-large wp-image-378\" alt=\"\" srcset=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/04\/IMG_3591-768x1024.jpg 768w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/04\/IMG_3591-225x300.jpg 225w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/04\/IMG_3591-1152x1536.jpg 1152w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/04\/IMG_3591-9x12.jpg 9w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2026\/04\/IMG_3591.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aca293 e-flex e-con-boxed e-con e-child\" data-id=\"3aca293\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-574be9e elementor-widget elementor-widget-image\" data-id=\"574be9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2025\/10\/IMG_8437-768x1024.png\" class=\"attachment-large size-large wp-image-73\" alt=\"\" srcset=\"https:\/\/keepgomarket.com\/wp-content\/uploads\/2025\/10\/IMG_8437-768x1024.png 768w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2025\/10\/IMG_8437-225x300.png 225w, https:\/\/keepgomarket.com\/wp-content\/uploads\/2025\/10\/IMG_8437.png 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64a91903 e-con-full e-flex e-con e-child\" data-id=\"64a91903\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-439ab56c e-flex e-con-boxed e-con e-child\" data-id=\"439ab56c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ff0539c elementor-widget elementor-widget-heading\" data-id=\"7ff0539c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Seguran\u00e7a e controle<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e078b5 elementor-widget elementor-widget-text-editor\" data-id=\"17e078b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A Keep &amp; Go opera com sistema de monitoramento por c\u00e2meras, controle de acesso conforme as regras do local e acompanhamento constante da opera\u00e7\u00e3o. O condom\u00ednio n\u00e3o assume riscos financeiros nem operacionais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ac41cd7 e-flex e-con-boxed e-con e-parent\" data-id=\"7ac41cd7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27971b30 e-con-full e-flex e-con e-child\" data-id=\"27971b30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a85bfe7 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"3a85bfe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a984416c5a51\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-3a85bfe7\">\n                        <a href=\"#collapse-a5bff506a984416c5a51\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a5bff506a984416c5a51\" aria-expanded=\"false\" aria-controls=\"Collapse-a5bff506a984416c5a51\">\n                            \n                            <span class=\"ekit-accordion-title\">O mercado aut\u00f4nomo aumenta a circula\u00e7\u00e3o de pessoas no condom\u00ednio?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a5bff506a984416c5a51\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-3a85bfe7\" data-parent=\"#accordion-6a984416c5a51\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">N\u00e3o. O acesso ao minimercado \u00e9 <\/span><b>restrito aos moradores, colaboradores ou visitantes autorizados<\/b><span style=\"font-weight: 400\">, seguindo as regras do pr\u00f3prio local. A Keep &amp; Go <\/span><b>n\u00e3o abre o espa\u00e7o ao p\u00fablico externo<\/b><span style=\"font-weight: 400\">.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-3a85bfe7\">\n                        <a href=\"#collapse-4b5f5a76a984416c5a51\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4b5f5a76a984416c5a51\" aria-expanded=\"false\" aria-controls=\"Collapse-4b5f5a76a984416c5a51\">\n                            \n                            <span class=\"ekit-accordion-title\"> O mercado traz riscos \u00e0 seguran\u00e7a?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4b5f5a76a984416c5a51\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-3a85bfe7\" data-parent=\"#accordion-6a984416c5a51\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">N\u00e3o. As lojas contam com <\/span><b>monitoramento por c\u00e2meras, controle de acesso e opera\u00e7\u00e3o supervisionada<\/b><span style=\"font-weight: 400\">. Al\u00e9m disso, o modelo aut\u00f4nomo reduz a necessidade de terceiros circulando no condom\u00ednio.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-3a85bfe7\">\n                        <a href=\"#collapse-46717816a984416c5a51\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-46717816a984416c5a51\" aria-expanded=\"false\" aria-controls=\"Collapse-46717816a984416c5a51\">\n                            \n                            <span class=\"ekit-accordion-title\">O condom\u00ednio ou empresa tem algum custo para instalar?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-46717816a984416c5a51\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-3a85bfe7\" data-parent=\"#accordion-6a984416c5a51\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">N\u00e3o. A implanta\u00e7\u00e3o do minimercado <\/span><b>n\u00e3o gera custo para o condom\u00ednio ou empresa<\/b><span style=\"font-weight: 400\">. A Keep &amp; Go assume os investimentos necess\u00e1rios para instala\u00e7\u00e3o e opera\u00e7\u00e3o.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-3a85bfe7\">\n                        <a href=\"#collapse-246fb736a984416c5a51\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-246fb736a984416c5a51\" aria-expanded=\"false\" aria-controls=\"Collapse-246fb736a984416c5a51\">\n                            \n                            <span class=\"ekit-accordion-title\">O condom\u00ednio recebe algum benef\u00edcio financeiro?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-246fb736a984416c5a51\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-3a85bfe7\" data-parent=\"#accordion-6a984416c5a51\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">Sim. Existe <\/span><b>comissionamento sobre as vendas<\/b><span style=\"font-weight: 400\">, que gera recursos extras para o condom\u00ednio.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-3a85bfe7\">\n                        <a href=\"#collapse-0cf8ea86a984416c5a51\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0cf8ea86a984416c5a51\" aria-expanded=\"false\" aria-controls=\"Collapse-0cf8ea86a984416c5a51\">\n                            \n                            <span class=\"ekit-accordion-title\">Os pre\u00e7os s\u00e3o mais caros que no supermercado?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0cf8ea86a984416c5a51\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-3a85bfe7\" data-parent=\"#accordion-6a984416c5a51\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">Os pre\u00e7os s\u00e3o praticados de forma <\/span><b>justa e equilibrada<\/b><span style=\"font-weight: 400\">, considerando a <\/span><b>conveni\u00eancia de ter o mercado dentro do local<\/b><span style=\"font-weight: 400\">. N\u00e3o h\u00e1 abusos, e o foco \u00e9 oferecer boa variedade, qualidade e praticidade.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30b4c7c e-con-full e-flex e-con e-child\" data-id=\"30b4c7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d5cb3b7 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"7d5cb3b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a984416c6673\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-7d5cb3b7\">\n                        <a href=\"#collapse-a5bff506a984416c6673\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a5bff506a984416c6673\" aria-expanded=\"false\" aria-controls=\"Collapse-a5bff506a984416c6673\">\n                            \n                            <span class=\"ekit-accordion-title\">O que acontece se algu\u00e9m pegar um produto e n\u00e3o pagar?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a5bff506a984416c6673\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-7d5cb3b7\" data-parent=\"#accordion-6a984416c6673\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">A responsabilidade \u00e9 da <\/span><b>Keep &amp; Go<\/b><span style=\"font-weight: 400\">, n\u00e3o do condom\u00ednio. O caso \u00e9 tratado diretamente pela opera\u00e7\u00e3o, sem qualquer preju\u00edzo financeiro para o empreendimento.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-7d5cb3b7\">\n                        <a href=\"#collapse-4b5f5a76a984416c6673\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4b5f5a76a984416c6673\" aria-expanded=\"false\" aria-controls=\"Collapse-4b5f5a76a984416c6673\">\n                            \n                            <span class=\"ekit-accordion-title\">Como funciona a reposi\u00e7\u00e3o e o controle de validade?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4b5f5a76a984416c6673\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-7d5cb3b7\" data-parent=\"#accordion-6a984416c6673\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">A reposi\u00e7\u00e3o \u00e9 feita de forma <\/span><b>frequente e personalizada<\/b><span style=\"font-weight: 400\">, conforme o perfil e o consumo de cada local. A equipe realiza <\/span><b>controle de validade, organiza\u00e7\u00e3o e limpeza<\/b><span style=\"font-weight: 400\"> regularmente.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-7d5cb3b7\">\n                        <a href=\"#collapse-46717816a984416c6673\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-46717816a984416c6673\" aria-expanded=\"false\" aria-controls=\"Collapse-46717816a984416c6673\">\n                            \n                            <span class=\"ekit-accordion-title\">Quais formas de pagamento s\u00e3o aceitas?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-46717816a984416c6673\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-7d5cb3b7\" data-parent=\"#accordion-6a984416c6673\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">PIX, cart\u00f5es de cr\u00e9dito e d\u00e9bito e, em alguns casos, vouchers. O pagamento \u00e9 feito diretamente no totem, de forma simples e r\u00e1pida.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-7d5cb3b7\">\n                        <a href=\"#collapse-57fa1d16a984416c6673\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-57fa1d16a984416c6673\" aria-expanded=\"false\" aria-controls=\"Collapse-57fa1d16a984416c6673\">\n                            \n                            <span class=\"ekit-accordion-title\">O mercado funciona 24 horas?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-57fa1d16a984416c6673\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-7d5cb3b7\" data-parent=\"#accordion-6a984416c6673\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">Sim. As lojas Keep &amp; Go funcionam <\/span><b>24h por dia, 7 dias por semana<\/b><span style=\"font-weight: 400\">, garantindo conveni\u00eancia total aos usu\u00e1rios.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-7d5cb3b7\">\n                        <a href=\"#collapse-dfb68f16a984416c6673\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-dfb68f16a984416c6673\" aria-expanded=\"false\" aria-controls=\"Collapse-dfb68f16a984416c6673\">\n                            \n                            <span class=\"ekit-accordion-title\">O espa\u00e7o precisa ser grande?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-dfb68f16a984416c6673\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-7d5cb3b7\" data-parent=\"#accordion-6a984416c6673\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">N\u00e3o. Os projetos s\u00e3o <\/span><b>personalizados<\/b><span style=\"font-weight: 400\"> e adaptados ao espa\u00e7o dispon\u00edvel, sempre buscando o melhor aproveitamento com o menor impacto poss\u00edvel na \u00e1rea comum.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-605ba1a0 e-flex e-con-boxed e-con e-parent\" data-id=\"605ba1a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-189f25ad e-flex e-con-boxed e-con e-child\" data-id=\"189f25ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70658b9e elementor-widget elementor-widget-heading\" data-id=\"70658b9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ainda tem d\u00favidas? Fale com a Keep &amp; Go e receba atendimento personalizado.\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c1a44fa e-flex e-con-boxed e-con e-child\" data-id=\"2c1a44fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b4f80 elementor-button-align-start elementor-widget elementor-widget-form\" data-id=\"d2b4f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Pr\\u00f3ximo&quot;,&quot;step_previous_label&quot;:&quot;Anterior&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Quero Contratar\" aria-label=\"Quero Contratar\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"131\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"d2b4f80\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_440116d elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_440116d\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tSobrenome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_440116d]\" id=\"form-field-field_440116d\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Sobrenome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-60 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail para contato\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_bcedee6 elementor-col-40 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_bcedee6\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tWhatsApp\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_bcedee6]\" id=\"form-field-field_bcedee6\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"WhatsApp\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Solo se aceptan n\u00fameros y caracteres de tel\u00e9fono (#,-,*,etc).\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_86b9f4f elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_86b9f4f\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCidade\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_86b9f4f]\" id=\"form-field-field_86b9f4f\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Cidade \/ ES\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_6e9fd9a elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6e9fd9a\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAssunto\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_6e9fd9a]\" id=\"form-field-field_6e9fd9a\" class=\"elementor-field-textual elementor-size-sm\">\n\t\t\t\t\t\t\t\t\t<option value=\"Quero a Keep &amp; Go no meu condom\u00ednio ou empresa\">Quero a Keep &amp; Go no meu condom\u00ednio ou empresa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Quero ser franqueado\">Quero ser franqueado<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"D\u00favidas gerais\">D\u00favidas gerais<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"8\" placeholder=\"Mensagem\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Leve a Keep &amp; Go para o seu espa\u00e7o Um minimercado aut\u00f4nomo que valoriza o empreendimento e facilita a rotina de quem utiliza. Solicitar proposta Onde a Keep &amp; Go pode estar Condom\u00ednios residenciais Condom\u00ednios comerciais Empresas e escrit\u00f3rios Empreendimentos novos ou j\u00e1 em opera\u00e7\u00e3o Atende todas as responsabilidades e exig\u00eancias necess\u00e1rias perante os \u00f3rg\u00e3os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-131","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/pages\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":34,"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/pages\/131\/revisions"}],"predecessor-version":[{"id":590,"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/pages\/131\/revisions\/590"}],"wp:attachment":[{"href":"https:\/\/keepgomarket.com\/en\/wp-json\/wp\/v2\/media?parent=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}